{"id":420,"date":"2019-04-07T11:06:53","date_gmt":"2019-04-07T11:06:53","guid":{"rendered":"https:\/\/operafuoco.fr\/?page_id=420"},"modified":"2021-09-30T13:04:40","modified_gmt":"2021-09-30T13:04:40","slug":"troupe","status":"publish","type":"page","link":"https:\/\/operafuoco.fr\/en\/troupe\/","title":{"rendered":"Young Artists"},"content":{"rendered":"<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"473\" src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/03\/IMG_6821-1170x473.jpg\" alt=\"\" class=\"wp-image-236\" srcset=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/03\/IMG_6821-1170x473.jpg 1170w, https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/03\/IMG_6821-1170x473-300x121.jpg 300w, https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/03\/IMG_6821-1170x473-768x310.jpg 768w, https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/03\/IMG_6821-1170x473-1024x414.jpg 1024w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n\n\n\n<p class=\"huge-title\">Young Artists<\/p>\n\n\n\n<div class=\"wp-block-ugb-spacer ugb-spacer ugb-ca7aa01 ugb-spacer--v2 ugb-main-block\"><style>@media screen and (min-width:768px){.ugb-ca7aa01.ugb-spacer{height:30px}}<\/style><div class=\"ugb-inner-block\"><div class=\"ugb-block-content\"><div class=\"ugb-spacer--inner\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-ugb-spacer ugb-spacer ugb-1b3b2a0 ugb-spacer--v2 ugb-main-block\"><style>@media screen and (min-width:768px){.ugb-1b3b2a0.ugb-spacer{height:40px}}<\/style><div class=\"ugb-inner-block\"><div class=\"ugb-block-content\"><div class=\"ugb-spacer--inner\"><\/div><\/div><\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Young Artists 2017-2020<\/h4>\n\n\n \r\n\r\n\t\t<div class=\"wp-tsas-wrp tsas-enable-popup\" id=\"tsas-wrp-1\">\r\n\t  \t\t<div class=\"wp_teamshowcase_grid design-3\">\r\n\t\t\t\t<div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2020\/02\/Photo-Fuoco-Goussot.jpg\" alt=\"Julie Goussot &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-1\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Julie Goussot &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c Site internet de <a href=\"https:\/\/www.juliegoussot.com\/\">Julie Goussot\u00a0<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-1\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2020\/02\/Photo-Fuoco-Goussot.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Julie Goussot &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c Site internet de <a href=\"https:\/\/www.juliegoussot.com\/\">Julie Goussot\u00a0<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/portrait-Walendzik.jpg\" alt=\"Matthieu Walendzik &#8211; Baryton\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-2\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Matthieu Walendzik - Baritone<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-2\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/portrait-Walendzik.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Matthieu Walendzik - Baritone<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/portrait-Vultaggio.jpg\" alt=\"Justine Vultaggio &#8211; Mezzo-soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-3\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Justine Vultaggio &#8211; Mezzo-soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-3\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/portrait-Vultaggio.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Justine Vultaggio &#8211; Mezzo-soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-last wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/shelton-site.jpg\" alt=\"William Shelton &#8211; Contre-t\u00e9nor\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-4\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">William Shelton - Countertenor<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/william-shelton.com\">Site internet de William Shelton\u00a0<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-4\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/shelton-site.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">William Shelton - Countertenor<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/william-shelton.com\">Site internet de William Shelton\u00a0<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Louis-Roullier.jpg\" alt=\"Louis Roullier &#8211; Baryton-basse\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-5\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Louis Roullier - Bass-Baritone<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-5\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Louis-Roullier.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Louis Roullier - Bass-Baritone<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/IMG_7532.jpg\" alt=\"Bastien Rimondi &#8211; T\u00e9nor\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-6\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Bastien Rimondi - Tenor<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-6\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/IMG_7532.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Bastien Rimondi - Tenor<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Theodora-Raftis-photo-by-Dinah-Kaprou-2-scaled.jpg\" alt=\"Theodora Raftis &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-7\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Theodora Raftis &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/theodoraraftis.com\">Site internet de Theodora<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-7\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Theodora-Raftis-photo-by-Dinah-Kaprou-2-scaled.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Theodora Raftis &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/theodoraraftis.com\">Site internet de Theodora<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-last wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/portrait.jpg\" alt=\"Anne-Lise Polchlopek &#8211; Mezzo-soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-8\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Anne-Lise Polchlopek &#8211; Mezzo-soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-8\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/portrait.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Anne-Lise Polchlopek &#8211; Mezzo-soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/image1-1.jpg\" alt=\"Cyrielle Ndjiki Nya &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-9\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Cyrielle Ndjiki Nya &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/www.cyriellendjikinya.com\">Site internet de Cyrielle Ndjiki Nya<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-9\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/image1-1.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Cyrielle Ndjiki Nya &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/www.cyriellendjikinya.com\">Site internet de Cyrielle Ndjiki Nya<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Alexia-72dpi-for-screen-2_.jpg\" alt=\"Alexia Macbeth &#8211; Mezzo-soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-10\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Alexia Macbeth &#8211; Mezzo-soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/www.alexiamacbeth.com\">Site internet d&rsquo;Alexia Macbeth<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-10\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Alexia-72dpi-for-screen-2_.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Alexia Macbeth &#8211; Mezzo-soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/www.alexiamacbeth.com\">Site internet d&rsquo;Alexia Macbeth<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/image1-1.jpg\" alt=\"Adrien Fournaison &#8211; Baryton-basse\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-11\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Adrien Fournaison \u2013 Bass-Baritone<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-11\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/image1-1.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Adrien Fournaison \u2013 Bass-Baritone<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-last wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/Portrait-couleur-Fr\u00e9d\u00e9ric-Bayle-scaled.jpeg\" alt=\"Dania El Zein &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-12\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Dania El Zein &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/www.daniaelzein.com\/biographie\">Site internet de Dania El Zein<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-12\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/Portrait-couleur-Fr\u00e9d\u00e9ric-Bayle-scaled.jpeg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Dania El Zein &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/www.daniaelzein.com\/biographie\">Site internet de Dania El Zein<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/photo-pro.png\" alt=\"Olivier Gourdy &#8211; Baryton-basse\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-13\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Olivier Gourdy - Bass-Baritone<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-13\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/photo-pro.png) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Olivier Gourdy - Bass-Baritone<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/Unknown.jpeg\" alt=\"Ad\u00e8le Charvet &#8211; Mezzo-soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-14\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Ad\u00e8le Charvet &#8211; Mezzo-soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/adelecharvet.com\">Site internet d&rsquo;Ad\u00e8le Charvet<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-14\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/Unknown.jpeg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Ad\u00e8le Charvet &#8211; Mezzo-soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/adelecharvet.com\">Site internet d&rsquo;Ad\u00e8le Charvet<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/Bergeron-2018-1.jpg\" alt=\"Olivier Bergeron &#8211; Baryton\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-15\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Olivier Bergeron - Baritone<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/www.olivierbergeron.ca\">Site internet d&rsquo;Olivier Bergeron<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-15\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/Bergeron-2018-1.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Olivier Bergeron - Baritone<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/www.olivierbergeron.ca\">Site internet d&rsquo;Olivier Bergeron<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-last wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/IMG_3767-e1555952538425.jpg\" alt=\"Marco Angioloni &#8211; T\u00e9nor\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-16\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Marco Angioloni - Tenor<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"http:\/\/www.marcoangioloni.com\">Site internet de Marco Angioloni<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-16\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/IMG_3767-e1555952538425.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Marco Angioloni - Tenor<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"http:\/\/www.marcoangioloni.com\">Site internet de Marco Angioloni<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/Juliette-72dpi-for-screen-6_.jpg\" alt=\"Juliette Allen &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-17\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Juliette Allen &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/www.juliette-allen.com\">Site internet de Juliette Allen<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-17\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/Juliette-72dpi-for-screen-6_.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Juliette Allen &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/www.juliette-allen.com\">Site internet de Juliette Allen<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/AGUDELO-Andres-LD-e1555952407554.jpg\" alt=\"Andres Agudelo &#8211; T\u00e9nor\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-1-18\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Andr\u00e9s Agudelo - Tenor<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-1-18\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/04\/AGUDELO-Andres-LD-e1555952407554.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Andr\u00e9s Agudelo - Tenor<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div>\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\n\n\n\n<div class=\"wp-block-ugb-spacer ugb-spacer ugb-47f00c5 ugb-spacer--v2 ugb-main-block\"><style>@media screen and (min-width:768px){.ugb-47f00c5.ugb-spacer{height:30px}}<\/style><div class=\"ugb-inner-block\"><div class=\"ugb-block-content\"><div class=\"ugb-spacer--inner\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-ugb-divider ugb-divider ugb-9fde0cc ugb-divider--v2 ugb-divider--design-basic ugb-main-block\"><style>.ugb-9fde0cc hr.ugb-divider__hr{background-color:#dddddd !important;height:1px !important;width:50% !important;margin-left:auto !important;margin-right:auto !important}.ugb-9fde0cc .ugb-inner-block{text-align:center}<\/style><div class=\"ugb-inner-block\"><div class=\"ugb-block-content\"><hr class=\"ugb-divider__hr\"\/><\/div><\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Young Artists 2014-2016 <\/h4>\n\n\n \r\n\r\n\t\t<div class=\"wp-tsas-wrp tsas-enable-popup\" id=\"tsas-wrp-2\">\r\n\t  \t\t<div class=\"wp_teamshowcase_grid design-3\">\r\n\t\t\t\t<div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5361.jpg\" alt=\"Sophia Stern &#8211; Mezzo-soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-1\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Sophia Stern &#8211; Mezzo-soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-1\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5361.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Sophia Stern &#8211; Mezzo-soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5708.jpg\" alt=\"Sahy Ratianarinaivo &#8211; T\u00e9nor\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-2\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Sahy Ratianarinaivo - Tenor<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-2\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5708.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Sahy Ratianarinaivo - Tenor<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/24799581_10215273739055875_5838622033873932567_o.jpg\" alt=\"Beno\u00eet Rameau &#8211; T\u00e9nor\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-3\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Beno\u00eet Rameau - Tenor<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-3\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/24799581_10215273739055875_5838622033873932567_o.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Beno\u00eet Rameau - Tenor<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-last wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Axelle-Fanyo-2018.jpg\" alt=\"Axelle Fanyo &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-4\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Axelle Fanyo &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/axellefanyo.com\/biographie.php\">Site internet d&rsquo;Axelle Fanyo<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-4\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Axelle-Fanyo-2018.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Axelle Fanyo &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/axellefanyo.com\/biographie.php\">Site internet d&rsquo;Axelle Fanyo<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5130.jpg\" alt=\"Julie Prola &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-5\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Julie Prola &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/www.julieprola.net\">Site internet de Julie Prola<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-5\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5130.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Julie Prola &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/www.julieprola.net\">Site internet de Julie Prola<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5533.jpg\" alt=\"\u00c9tienne de B\u00e9naz\u00e9 &#8211; T\u00e9nor\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-6\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">\u00c9tienne de B\u00e9naz\u00e9 &#8211; T\u00e9nor<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-6\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5533.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">\u00c9tienne de B\u00e9naz\u00e9 &#8211; T\u00e9nor<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/LeaDesandreLD-copie.jpg\" alt=\"Lea Desandre &#8211; Mezzo-soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-7\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Lea Desandre &#8211; Mezzo-soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/www.leadesandre.com\">Site internet de Lea Desandre\u00a0<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-7\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/LeaDesandreLD-copie.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Lea Desandre &#8211; Mezzo-soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/www.leadesandre.com\">Site internet de Lea Desandre\u00a0<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-last wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5768.jpg\" alt=\"Jennifer Courcier &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-8\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Jennifer Courcier &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"http:\/\/jennifercourcier.com\">Site internet de Jennifer Courcier<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-8\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5768.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Jennifer Courcier &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"http:\/\/jennifercourcier.com\">Site internet de Jennifer Courcier<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/CANDELA-Martin-LD.jpg\" alt=\"Martin Candela &#8211; T\u00e9nor\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-9\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Martin Candela - Tenor<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/mcandela537522.wixsite.com\/candelamartin-tenor\">Site internet de Martin Candela<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-9\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/CANDELA-Martin-LD.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Martin Candela - Tenor<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/mcandela537522.wixsite.com\/candelamartin-tenor\">Site internet de Martin Candela<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5469-200x300.jpg\" alt=\"Alexandre Artemenko &#8211; Baryton\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-2-10\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Alexandre Artemenko - Baritone<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-2-10\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/M10_5469-200x300.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Alexandre Artemenko - Baritone<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div>\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\n\n\n\n<div class=\"wp-block-ugb-spacer ugb-spacer ugb-dd9ac09 ugb-spacer--v2 ugb-main-block\"><style>@media screen and (min-width:768px){.ugb-dd9ac09.ugb-spacer{height:30px}}<\/style><div class=\"ugb-inner-block\"><div class=\"ugb-block-content\"><div class=\"ugb-spacer--inner\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-ugb-divider ugb-divider ugb-318bf06 ugb-divider--v2 ugb-divider--design-basic ugb-main-block\"><style>.ugb-318bf06 hr.ugb-divider__hr{background-color:#dddddd !important;height:1px !important;width:50% !important;margin-left:auto !important;margin-right:auto !important}.ugb-318bf06 .ugb-inner-block{text-align:center}<\/style><div class=\"ugb-inner-block\"><div class=\"ugb-block-content\"><hr class=\"ugb-divider__hr\"\/><\/div><\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Past Members<\/h4>\n\n\n \r\n\r\n\t\t<div class=\"wp-tsas-wrp tsas-enable-popup\" id=\"tsas-wrp-3\">\r\n\t  \t\t<div class=\"wp_teamshowcase_grid design-3\">\r\n\t\t\t\t<div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2024\/05\/Capture-decran-2024-05-27-a-13.57.04.png\" alt=\"Pierrick Boisseau &#8211; Baryton\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-3-1\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Pierrick Boisseau &#8211; Baryton<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"https:\/\/pierrickboisseau.wixsite.com\/home\">Site Internet de Pierrick Boisseau<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-3-1\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2024\/05\/Capture-decran-2024-05-27-a-13.57.04.png) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Pierrick Boisseau &#8211; Baryton<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"https:\/\/pierrickboisseau.wixsite.com\/home\">Site Internet de Pierrick Boisseau<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2020\/11\/Marc-Callahan_-headshot.jpg\" alt=\"Marc Callahan &#8211; Baryton\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-3-2\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Marc Callahan - Baritone<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: small;\">[ Site personnel de Marc Callahan en cours de r\u00e9\u00e9dition ]\u00a0<\/span><\/span><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-3-2\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2020\/11\/Marc-Callahan_-headshot.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Marc Callahan - Baritone<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: small;\">[ Site personnel de Marc Callahan en cours de r\u00e9\u00e9dition ]\u00a0<\/span><\/span><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2020\/11\/2020-04-15-2.png\" alt=\"Luanda Siqueira &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-3-3\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Luanda Siqueira &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-3-3\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2020\/11\/2020-04-15-2.png) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Luanda Siqueira &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-last wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Sara-Hershkowitz-homeBIS.jpg\" alt=\"Sara Hershkowitz &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-3-4\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Sara Hershkowitz &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"http:\/\/sarahershkowitz.de\/\">Site internet de Sara Hershkowitz<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-3-4\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Sara-Hershkowitz-homeBIS.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Sara Hershkowitz &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"http:\/\/sarahershkowitz.de\/\">Site internet de Sara Hershkowitz<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/xl_avatar.jpg\" alt=\"Cl\u00e9mentine Margaine &#8211; Mezzo-soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-3-5\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Cl\u00e9mentine Margaine &#8211; Mezzo-soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"http:\/\/clementinemargaine.com\">Site internet de Cl\u00e9mentine Margaine<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-3-5\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/xl_avatar.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Cl\u00e9mentine Margaine &#8211; Mezzo-soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"http:\/\/clementinemargaine.com\">Site internet de Cl\u00e9mentine Margaine<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2020\/11\/Caroline-Meng-2.png\" alt=\"Caroline Meng &#8211; Mezzo-soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-3-6\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Caroline Meng &#8211; Mezzo-soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"http:\/\/www.carolinemeng.com\">Site internet de Caroline Meng<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-3-6\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2020\/11\/Caroline-Meng-2.png) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Caroline Meng &#8211; Mezzo-soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"http:\/\/www.carolinemeng.com\">Site internet de Caroline Meng<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/NPEREZ-Anciens-V2.jpg\" alt=\"Natalie P\u00e9rez &#8211; Mezzo-soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-3-7\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Natalie P\u00e9rez &#8211; Mezzo-soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"http:\/\/www.natalieperezsoprano.com\/\">Site internet de Natalie P\u00e9rez<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-3-7\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/NPEREZ-Anciens-V2.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Natalie P\u00e9rez &#8211; Mezzo-soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"http:\/\/www.natalieperezsoprano.com\/\">Site internet de Natalie P\u00e9rez<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-last wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Chantal-SantonBIS.jpg\" alt=\"Chantal Santon Jeffery &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-3-8\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Chantal Santon Jeffery &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"http:\/\/www.chantalsanton.com\/\">Site internet de Chantal Santon Jeffery<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-3-8\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Chantal-SantonBIS.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Chantal Santon Jeffery &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"http:\/\/www.chantalsanton.com\/\">Site internet de Chantal Santon Jeffery<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div><div class=\"team-grid tsas-first wp-tsas-medium-3 wp-tsas-columns\">\r\n\t<div class=\"teamshowcase-image-bg\">\r\n\t\t<img decoding=\"async\"  src=\"https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Vannina-Santoni-Studio-Harcourt.jpg\" alt=\"Vannina Santoni &#8211; Soprano\" \/>\r\n\t\t\t\t\t<a class=\"teamshowcase-hover-icon popup-modal\" data-mfp-src=\"#popup-3-9\" href=\"javascript:void(0);\"><i class=\"fa fa-plus-circle\"><\/i><\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-main-info\">\r\n\t\t<div class=\"member-name\">Vannina Santoni &#8211; Soprano<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"member-content\">\r\n\t\t<div class=\"member-desc\">\r\n\t\t\t<p>\u279c <a href=\"http:\/\/www.vanninasantoni.com\/\">Site internet de Vannina Santoni<\/a><\/p>\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<\/div>\r\n<div id=\"popup-3-9\" class=\"mfp-hide white-popup-block wp-tsas-popup-wrp\">\r\n\t<header>\r\n\t\t<div class=\"wp-modal-header ng-scope\" style=\"background:url(https:\/\/operafuoco.fr\/wp-content\/uploads\/2019\/05\/Vannina-Santoni-Studio-Harcourt.jpg) center top no-repeat;\">\r\n\t\t\t<div class=\"member-popup-info\">\r\n\t\t\t\t<div class=\"member-name\">Vannina Santoni &#8211; Soprano<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/header>\r\n\r\n\t<div class=\"wp-modal-body\">\r\n\t\t<p>\u279c <a href=\"http:\/\/www.vanninasantoni.com\/\">Site internet de Vannina Santoni<\/a><\/p>\n\t<\/div>\r\n\r\n<\/div>\t\t\t<\/div>\r\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Troupe La troupe 2017-2020 La troupe 2014-2016 Les Anciens<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":28,"comment_status":"closed","ping_status":"closed","template":"","meta":{"qubely_global_settings":"","qubely_interactions":"","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","kk_blocks_editor_width":"","_kiokenblocks_attr":"","_kiokenblocks_dimensions":"","_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-420","page","type-page","status-publish","hentry"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","thumblist":"","meccarouselthumb":"","gridsquare":"","tileview":"","1536x1536":"","2048x2048":"","trp-custom-language-flag":"","qubely_landscape":"","qubely_portrait":"","qubely_thumbnail":"","vp_sm":"","vp_md":"","vp_lg":"","vp_xl":"","vp_sm_popup":"","vp_md_popup":"","vp_xl_popup":""},"post_excerpt_stackable":"<p>Troupe La troupe 2017-2020 Julie Goussot &#8211; Soprano \u279c Site internet de Julie Goussot\u00a0 Julie Goussot &#8211; Soprano \u279c Site internet de Julie Goussot\u00a0 Matthieu Walendzik &#8211; Baryton Matthieu Walendzik &#8211; Baryton Justine Vultaggio &#8211; Mezzo-soprano Justine Vultaggio &#8211; Mezzo-soprano William Shelton &#8211; Contre-t\u00e9nor \u279c Site internet de William Shelton\u00a0 William Shelton &#8211; Contre-t\u00e9nor \u279c Site internet de William Shelton\u00a0 Louis Roullier &#8211; Baryton-basse Louis Roullier &#8211; Baryton-basse Bastien Rimondi &#8211; T\u00e9nor Bastien Rimondi &#8211; T\u00e9nor Theodora Raftis &#8211; Soprano \u279c Site internet de Theodora Theodora Raftis &#8211; Soprano \u279c Site internet de Theodora Anne-Lise Polchlopek &#8211; Mezzo-soprano Anne-Lise Polchlopek&hellip;<\/p>\n","category_list":"","author_info":{"name":"admin","url":"https:\/\/operafuoco.fr\/en\/author\/admin\/"},"comments_num":"0 comments","aioseo_notices":[],"featured_image_src":"","featured_image_src_square":false,"rbea_author_info":{"display_name":"admin","author_link":"https:\/\/operafuoco.fr\/en\/author\/admin\/"},"rbea_excerpt_info":"Troupe La troupe 2017-2020 La troupe 2014-2016 Les Anciens","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"thumblist":false,"meccarouselthumb":false,"gridsquare":false,"tileview":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"qubely_landscape":false,"qubely_portrait":false,"qubely_thumbnail":false,"vp_sm":false,"vp_md":false,"vp_lg":false,"vp_xl":false,"vp_sm_popup":false,"vp_md_popup":false,"vp_xl_popup":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/operafuoco.fr\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Troupe La troupe 2017-2020 La troupe 2014-2016 Les Anciens","_links":{"self":[{"href":"https:\/\/operafuoco.fr\/en\/wp-json\/wp\/v2\/pages\/420"}],"collection":[{"href":"https:\/\/operafuoco.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/operafuoco.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/operafuoco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/operafuoco.fr\/en\/wp-json\/wp\/v2\/comments?post=420"}],"version-history":[{"count":32,"href":"https:\/\/operafuoco.fr\/en\/wp-json\/wp\/v2\/pages\/420\/revisions"}],"predecessor-version":[{"id":3028,"href":"https:\/\/operafuoco.fr\/en\/wp-json\/wp\/v2\/pages\/420\/revisions\/3028"}],"wp:attachment":[{"href":"https:\/\/operafuoco.fr\/en\/wp-json\/wp\/v2\/media?parent=420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}